{"id":3545,"date":"2025-11-06T14:58:44","date_gmt":"2025-11-06T14:58:44","guid":{"rendered":"https:\/\/jimo.pt\/?post_type=portfolio&#038;p=3545"},"modified":"2025-11-06T15:15:19","modified_gmt":"2025-11-06T15:15:19","slug":"apollo-2","status":"publish","type":"portfolio","link":"https:\/\/jimo.pt\/fr\/produtos\/apollo-2\/","title":{"rendered":"APOLLO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3545\" class=\"elementor elementor-3545\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6d2406 e-flex e-con-boxed e-con e-parent\" data-id=\"f6d2406\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-192d3c2 e-con-full e-flex e-con e-child\" data-id=\"192d3c2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:40,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b86926a elementor-widget elementor-widget-image\" data-id=\"b86926a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1531\" height=\"798\" src=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/modular-apollo-decoracao-jimo.png\" class=\"attachment-full size-full wp-image-3546\" alt=\"\" srcset=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/modular-apollo-decoracao-jimo.png 1531w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/modular-apollo-decoracao-jimo-300x156.png 300w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/modular-apollo-decoracao-jimo-1024x534.png 1024w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/modular-apollo-decoracao-jimo-768x400.png 768w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/modular-apollo-decoracao-jimo-650x339.png 650w\" sizes=\"(max-width: 1531px) 100vw, 1531px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-770ea1a e-con-full e-flex e-con e-child\" data-id=\"770ea1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6932194 elementor-widget elementor-widget-heading\" data-id=\"6932194\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><span>Vitrines Pastelaria\/Cafetaria<\/span><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd291f8 elementor-widget elementor-widget-heading\" data-id=\"dd291f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">APOLLO<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d68487e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d68487e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Decora\u00e7\u00e3o em mdf revestido a faia com velatura<\/li><li>Tampo de servi\u00e7o em granito<\/li><li>Rodap\u00e9 em a\u00e7o inox inclinado com ilumina\u00e7\u00e3o (S\u00f3 dispon\u00edvel em a\u00e7o inox)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5550dbf e-con-full e-flex e-con e-child\" data-id=\"5550dbf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c54be5a elementor-widget elementor-widget-heading\" data-id=\"c54be5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Informa\u00e7\u00f5es e Or\u00e7amento<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8e34f eael-wpforms-form-button-custom elementor-widget elementor-widget-eael-wpforms\" data-id=\"ee8e34f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-wpforms.default\">\n\t\t\t\t\t            <div class=\"eael-contact-form eael-wpforms eael-wpforms-align-default\">\n                                <div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-683\"><form id=\"wpforms-form-683\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"683\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/portfolio\/3545\" data-token=\"19b577296517e7d60d8eead47e77141d\" data-token-time=\"1778677835\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-683-field_3-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"3\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-683-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-683-field_1\" aria-hidden=\"false\">Nome <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-683-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Nome\" aria-errormessage=\"wpforms-683-field_1-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-683-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-683-field_2\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-683-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-683-field_2-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-683-field_4-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-683-field_4\" aria-hidden=\"false\">Contacto<\/label><input type=\"tel\" id=\"wpforms-683-field_4\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][4]\" placeholder=\"Contacto\" aria-label=\"Contacto\" aria-errormessage=\"wpforms-683-field_4-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-683-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-683-field_5\" aria-hidden=\"false\">Empresa<\/label><input type=\"text\" id=\"wpforms-683-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" placeholder=\"Empresa (opcional)\" aria-errormessage=\"wpforms-683-field_5-error\" ><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-683-field_6-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-683-field_6\" aria-hidden=\"false\">Mensagem<\/label><textarea id=\"wpforms-683-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" placeholder=\"Mensagem\" aria-errormessage=\"wpforms-683-field_6-error\" ><\/textarea><\/div>\t\t<div id=\"wpforms-683-field_8-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"8\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-683-field_8\" >Dados Email Nome<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-683-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-683-field_7-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"7\"><label class=\"wpforms-field-label\">RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-683-field_7\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-683-field_7_1\" name=\"wpforms[fields][7][]\" value=\"Confirmo que li e aceito a &lt;a target=&quot;_blank&quot; href=&quot;https:\/\/jimo.pt\/politica-de-privacidade\/&quot;&gt;pol\u00edtica de privacidade&lt;\/a&gt;.\" aria-errormessage=\"wpforms-683-field_7_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-683-field_7_1\">Confirmo que li e aceito a <a target=\"_blank\" href=\"https:\/\/jimo.pt\/politica-de-privacidade\/\">pol\u00edtica de privacidade<\/a>.<\/label><\/li><\/ul><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-683-field_8-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-683-field_8-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-683-field_8-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"683\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/portfolio\/3545\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-683\" class=\"wpforms-submit\" data-alt-text=\"A enviar...\" data-submit-text=\"Enviar Pedido\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar Pedido<\/button><img decoding=\"async\" src=\"https:\/\/jimo.pt\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e55802 elementor-widget elementor-widget-spacer\" data-id=\"3e55802\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b2cb52 e-flex e-con-boxed e-con e-parent\" data-id=\"4b2cb52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3704ff3 e-con-full e-flex e-con e-child\" data-id=\"3704ff3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-839d5e9 elementor-widget elementor-widget-heading\" data-id=\"839d5e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Exemplo de imagem (representativa)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ec395 elementor-widget elementor-widget-image\" data-id=\"e1ec395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"717\" src=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1.png\" class=\"attachment-full size-full wp-image-3548\" alt=\"\" srcset=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1.png 2048w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1-300x105.png 300w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1-1024x359.png 1024w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1-768x269.png 768w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1-1536x538.png 1536w, https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/Sem-titulo-1-e1581701205853-2048x717-1-650x228.png 650w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc174b0 elementor-widget elementor-widget-button\" data-id=\"bc174b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/APOLLO.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download de Caracter\u00edsticas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f9794 e-n-tabs-none elementor-widget elementor-widget-n-tabs\" data-id=\"f9f9794\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;center&quot;,&quot;tabs_justify_horizontal_mobile&quot;:&quot;center&quot;,&quot;horizontal_scroll_mobile&quot;:&quot;disable&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"262117268\" aria-label=\"Separadores. Abra itens com Enter ou Espa\u00e7o, feche com Escape e navegue utilizando as teclas de setas.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2621172681\" data-tab-title-id=\"e-n-tab-title-2621172681\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2621172681\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tBalc\u00e3o\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2621172682\" data-tab-title-id=\"e-n-tab-title-2621172682\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2621172682\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tM\u00f3dulo de Apoio\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2621172683\" data-tab-title-id=\"e-n-tab-title-2621172683\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2621172683\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tVitrines\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2621172681\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2621172681\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-6cb1d7d e-con-full e-flex e-con e-child\" data-id=\"6cb1d7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4556192 elementor-widget elementor-widget-image\" data-id=\"4556192\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"138\" height=\"200\" src=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/APOLLO_Balcoes-1-e1581418500458.png\" class=\"attachment-large size-large wp-image-3556\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2621172682\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2621172682\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-14144e3 e-con-full e-flex e-con e-child\" data-id=\"14144e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8050a57 elementor-widget elementor-widget-image\" data-id=\"8050a57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"166\" height=\"200\" src=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/APOLLO_Balcao-de-Apoio-1-e1581418509259.png\" class=\"attachment-large size-large wp-image-3557\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2621172683\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2621172683\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-02b2f8e e-con-full e-flex e-con e-child\" data-id=\"02b2f8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed2dd22 elementor-widget elementor-widget-image\" data-id=\"ed2dd22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"162\" height=\"200\" src=\"https:\/\/jimo.pt\/wp-content\/uploads\/2025\/11\/APOLLO_Vitrine-1-e1581418519381.png\" class=\"attachment-large size-large wp-image-3558\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Decora\u00e7\u00e3o em mdf revestido a faia com velatura Tampo de servi\u00e7o em granito Rodap\u00e9 em a\u00e7o inox inclinado com ilumina\u00e7\u00e3o (S\u00f3 dispon\u00edvel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3546,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"portfolio_category":[12],"class_list":["post-3545","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-vitrines-pastelaria-cafetaria"],"_links":{"self":[{"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/portfolio\/3545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/comments?post=3545"}],"version-history":[{"count":10,"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/portfolio\/3545\/revisions"}],"predecessor-version":[{"id":3574,"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/portfolio\/3545\/revisions\/3574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/media\/3546"}],"wp:attachment":[{"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/media?parent=3545"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/jimo.pt\/fr\/wp-json\/wp\/v2\/portfolio_category?post=3545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}